{"id":7,"date":"2015-10-09T19:20:38","date_gmt":"2015-10-09T17:20:38","guid":{"rendered":"http:\/\/grantourdellecolline.rucola.hiho.it\/?page_id=7"},"modified":"2018-12-22T13:24:22","modified_gmt":"2018-12-22T12:24:22","slug":"home","status":"publish","type":"page","link":"https:\/\/www.grantourdellecolline.it\/it\/","title":{"rendered":"Home"},"content":{"rendered":"<p>ita<\/p>","protected":false},"excerpt":{"rendered":"<p>ita<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/business.php","meta":{"footnotes":""},"class_list":["post-7","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gran Tour delle Colline<\/title>\n<meta name=\"description\" content=\"Il Circolo Fotografico Arno, con i Patrocini di FIAP, PSA, UPI, ISF e FIAF, organizza il circuito internazionale di concorsi fotografici, per immagini digitali, &quot;20\u00b0 GRAN TOUR DELLE COLLINE\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grantourdellecolline.it\/en\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gran Tour delle Colline\" \/>\n<meta property=\"og:description\" content=\"Il Circolo Fotografico Arno, con i Patrocini di FIAP, PSA, UPI, ISF e FIAF, organizza il circuito internazionale di concorsi fotografici, per immagini digitali, &quot;20\u00b0 GRAN TOUR DELLE COLLINE\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grantourdellecolline.it\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Gran Tour delle Colline\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-22T12:24:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grantourdellecolline.it\/wp-content\/uploads\/2017\/11\/gran-tour-delle-colline.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1758\" \/>\n\t<meta property=\"og:image:height\" content=\"1005\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/\",\"url\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/\",\"name\":\"Gran Tour delle Colline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#website\"},\"datePublished\":\"2015-10-09T17:20:38+00:00\",\"dateModified\":\"2018-12-22T12:24:22+00:00\",\"description\":\"Il Circolo Fotografico Arno, con i Patrocini di FIAP, PSA, UPI, ISF e FIAF, organizza il circuito internazionale di concorsi fotografici, per immagini digitali, \\\"20\u00b0 GRAN TOUR DELLE COLLINE\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/\",\"name\":\"Gran Tour delle Colline\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#organization\",\"name\":\"Gran Tour delle Colline\",\"url\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/grantourdellecolline-sharing.png\",\"contentUrl\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/grantourdellecolline-sharing.png\",\"width\":600,\"height\":316,\"caption\":\"Gran Tour delle Colline\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grantourdellecolline.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gran Tour delle Colline","description":"Il Circolo Fotografico Arno, con i Patrocini di FIAP, PSA, UPI, ISF e FIAF, organizza il circuito internazionale di concorsi fotografici, per immagini digitali, \"20\u00b0 GRAN TOUR DELLE COLLINE\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grantourdellecolline.it\/en\/","og_locale":"it_IT","og_type":"article","og_title":"Gran Tour delle Colline","og_description":"Il Circolo Fotografico Arno, con i Patrocini di FIAP, PSA, UPI, ISF e FIAF, organizza il circuito internazionale di concorsi fotografici, per immagini digitali, \"20\u00b0 GRAN TOUR DELLE COLLINE\u201d.","og_url":"https:\/\/www.grantourdellecolline.it\/en\/","og_site_name":"Gran Tour delle Colline","article_modified_time":"2018-12-22T12:24:22+00:00","og_image":[{"width":1758,"height":1005,"url":"https:\/\/www.grantourdellecolline.it\/wp-content\/uploads\/2017\/11\/gran-tour-delle-colline.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.grantourdellecolline.it\/en\/","url":"https:\/\/www.grantourdellecolline.it\/en\/","name":"Gran Tour delle Colline","isPartOf":{"@id":"https:\/\/www.grantourdellecolline.it\/en\/#website"},"datePublished":"2015-10-09T17:20:38+00:00","dateModified":"2018-12-22T12:24:22+00:00","description":"Il Circolo Fotografico Arno, con i Patrocini di FIAP, PSA, UPI, ISF e FIAF, organizza il circuito internazionale di concorsi fotografici, per immagini digitali, \"20\u00b0 GRAN TOUR DELLE COLLINE\u201d.","breadcrumb":{"@id":"https:\/\/www.grantourdellecolline.it\/en\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grantourdellecolline.it\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grantourdellecolline.it\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.grantourdellecolline.it\/en\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.grantourdellecolline.it\/en\/#website","url":"https:\/\/www.grantourdellecolline.it\/en\/","name":"Gran Tour delle Colline","description":"","publisher":{"@id":"https:\/\/www.grantourdellecolline.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grantourdellecolline.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.grantourdellecolline.it\/en\/#organization","name":"Gran Tour delle Colline","url":"https:\/\/www.grantourdellecolline.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.grantourdellecolline.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.grantourdellecolline.it\/wp-content\/uploads\/2015\/10\/grantourdellecolline-sharing.png","contentUrl":"https:\/\/www.grantourdellecolline.it\/wp-content\/uploads\/2015\/10\/grantourdellecolline-sharing.png","width":600,"height":316,"caption":"Gran Tour delle Colline"},"image":{"@id":"https:\/\/www.grantourdellecolline.it\/en\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":false,"_links":{"self":[{"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/pages\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/comments?post=7"}],"version-history":[{"count":2,"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/pages\/7\/revisions"}],"predecessor-version":[{"id":527,"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/pages\/7\/revisions\/527"}],"wp:attachment":[{"href":"https:\/\/www.grantourdellecolline.it\/it\/wp-json\/wp\/v2\/media?parent=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}